{"id":6481,"date":"2020-01-31T15:25:03","date_gmt":"2020-01-31T15:25:03","guid":{"rendered":"https:\/\/montage-demo.azds.com\/palmettobluff\/accommodations\/village-home-33\/"},"modified":"2025-11-12T11:28:23","modified_gmt":"2025-11-12T15:28:23","slug":"village-home-33","status":"publish","type":"accommodation","link":"https:\/\/www.montage.com\/palmettobluff\/accommodations\/village-home-33\/","title":{"rendered":"5 Bedroom Wilson Village Home 33"},"content":{"rendered":"<div id=\"accommodations\" class=\"hero\">\n    <div class=\"hero__container swiper-container hero__container-- \">\n        <div class=\"hero__wrapper hero__wrapper--  \">\n                                <div class=\"hero__slide hero__slide--  \">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc251b2b743761642.jpg\" alt=\"5 Bedroom Wilson Village Home 33 1\" width=\"1620\" height=\"1080\" class=\"hero__image \">\n            <\/div>\n                    <\/div>\n\n        \n\n        \n    <\/div>\n\n    \n            <div class=\"hero__accommodation\">\n                            <h1 class=\"hero__title\">5 Bedroom Wilson Village Home 33<\/h1>\n            \n                            <ul class=\"hero__list\">\n                                            <li class=\"hero__item\">\n                                                            <a href=\"https:\/\/www.montage.com\/palmettobluff\/accommodations\/village-home-5036\/\" class=\"hero__link \">Home 5036<\/a>\n                                                    <\/li>\n                                            <li class=\"hero__item\">\n                                                            <span class=\"hero__link active\">Home 33<\/span>\n                                                    <\/li>\n                                            <li class=\"hero__item\">\n                                                            <a href=\"https:\/\/www.montage.com\/palmettobluff\/accommodations\/village-home-61\/\" class=\"hero__link \">Home 61<\/a>\n                                                    <\/li>\n                                            <li class=\"hero__item\">\n                                                            <a href=\"https:\/\/www.montage.com\/palmettobluff\/accommodations\/village-home-62\/\" class=\"hero__link \">Home 62<\/a>\n                                                    <\/li>\n                                            <li class=\"hero__item\">\n                                                            <a href=\"https:\/\/www.montage.com\/palmettobluff\/accommodations\/village-home-5048\/\" class=\"hero__link \">Home 5048<\/a>\n                                                    <\/li>\n                                    <\/ul>\n                    <\/div>\n    \n<\/div>\n\n\n<div id=\"village-home-33\" class=\"page-section page-section--intro-box-revraise\">\n    <div class=\"intro-box intro-box--revraise container\">\n        <div class=\"row justify-content-center\">\n            <div class=\"col-12 col-lg-10 intro-box__content text-center\">\n                                                    <div class=\"intro-box__description intro-box__description--revraise\"><p>Five Bedroom Wilson Village Home 33 makes a grand impression, with Victorian-inspired architecture facing a large, landscaped courtyard, with views overlooking the village lagoon.<\/p><\/div>\n                            <\/div>\n                            <div class=\"col-12 intro-box__provision intro-box__provision--revraise\">\n                    <div class=\"d-flex justify-content-center intro-box__provision-table\">\n                                                                                    <div class=\"intro-box__provision-row d-flex\">\n                                                        <div class=\"intro-box__provision-item intro-box__provision-item--first d-flex justify-content-center\">\n                                <div class=\"text-center\">\n                                    <div class=\"intro-box__provision-title intro-box__provision-title--revraise h3\">Beds<\/div>\n                                    <div class=\"intro-box__provision-caption intro-box__provision-caption--revraise\"><p>3 King &amp; 3 Queen<\/p>\n<\/div>\n                                <\/div>\n                            <\/div>\n                                                                                                            <div class=\"intro-box__provision-item d-flex justify-content-center\">\n                                <div class=\"text-center\">\n                                    <div class=\"intro-box__provision-title intro-box__provision-title--revraise h3\">Room Size<\/div>\n                                    <div class=\"intro-box__provision-caption intro-box__provision-caption--revraise\"><p>4,368 sq. ft.<\/p>\n<\/div>\n                                <\/div>\n                            <\/div>\n                                                            <\/div>\n                                                                                                                <div class=\"intro-box__provision-row d-flex\">\n                                                        <div class=\"intro-box__provision-item d-flex justify-content-center\">\n                                <div class=\"text-center\">\n                                    <div class=\"intro-box__provision-title intro-box__provision-title--revraise h3\">Occupancy<\/div>\n                                    <div class=\"intro-box__provision-caption intro-box__provision-caption--revraise\"><p>Up to 12 adults<\/p>\n<\/div>\n                                <\/div>\n                            <\/div>\n                                                                                                            <div class=\"intro-box__provision-item d-flex justify-content-center\">\n                                <div class=\"text-center\">\n                                    <div class=\"intro-box__provision-title intro-box__provision-title--revraise h3\">View<\/div>\n                                    <div class=\"intro-box__provision-caption intro-box__provision-caption--revraise\"><p>Lagoon<\/p>\n<\/div>\n                                <\/div>\n                            <\/div>\n                                                                                                            <div class=\"intro-box__provision-item intro-box__provision-item--last d-flex justify-content-center\">\n                                <div class=\"text-center\">\n                                    <div class=\"intro-box__provision-title intro-box__provision-title--revraise h3\">Bathroom<\/div>\n                                    <div class=\"intro-box__provision-caption intro-box__provision-caption--revraise\"><p>4.5<\/p>\n<\/div>\n                                <\/div>\n                            <\/div>\n                                                            <\/div>\n                                                                        <\/div>\n                <\/div>\n            \n                            <div class=\"intro-box__buttons intro-box__buttons--revraise intro-box__buttons-- col-12 text-center\">\n                                            <a href=\"https:\/\/www.montage.com\/palmettobluff\/montage-reservations\/#\/booking\/step-1?room=33\" target=\"_self\" class=\"intro-box__button c-button c-button--box c-button--grey\">Reserve this <\/a>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div id=\"accommodation-amenities\" class=\"accommodation-amenities\">\n    <div class=\"c-appeared\">\n        <div class=\"container\">\n            <div class=\"row accommodation-amenities__row\">\n                <div class=\"col-12 col-lg-6 accommodation-amenities__wrapper\">\n                    <!-- Sinxis image -->\n                    <img decoding=\"async\" src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc267924886934001.jpg\" width=\"1200\" height=\"761\" class=\"accommodation-amenities__image mb-3 mb-lg-0\" alt=\"5 Bedroom Wilson Village Home 33 2\" loading=\"lazy\">\n                <\/div>\n                <div class=\" col-12 col-lg-4 offset-lg-1 accommodation-amenities__content\">\n                                            <h2 class=\"accommodation-amenities__title mb-2 mb-lg-5\">\n                            Features &amp; amenities\n                        <\/h2>\n                    \n                                            <div class=\"accommodation-amenities__description\">\n                            <ul><li>Master suite has vaulted ceiling, large walk-in closet and direct access to screened porch<\/li><li>Master bath has claw-foot tub and separate glass walk-in shower<\/li><li>Expansive kitchen with large center island, breakfast bar, table for four<\/li><li>Stunning red-brick fireplace and separate wet bar area with a Viking cooler and ice maker<\/li><li>Dining room provides seating for six to eight<\/li><li>Great room has a fireplace, plenty of seating<\/li><li>50-inch flat screen TV plus a stereo with ceiling speakers, and multi-room music system<\/li><li>Den with a flat screen TV<\/li><li>Three king and three queen-size beds<\/li><li>4,368ft&sup2; \/ 406m&sup2;<\/li><li>Maximum 12 persons<\/li><\/ul>\n\n                            <button class=\"accommodation-amenities__read-more mt-3 d-lg-none\">Read More<\/button>\n                            <button class=\"accommodation-amenities__read-less mt-3 d-lg-none\">Read Less<\/button>\n                        <\/div>\n                    \n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div id=\"roomTourModal\" class=\"accomodations__dialog \">\n    <button type=\"button\" class=\"accomodations__dialog__button\" aria-label=\"close\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" width=\"100\" height=\"100\" viewbox=\"0 0 50 50\">\n            <path d=\"M 7.71875 6.28125 L 6.28125 7.71875 L 23.5625 25 L 6.28125 42.28125 L 7.71875 43.71875 L 25 26.4375 L 42.28125 43.71875 L 43.71875 42.28125 L 26.4375 25 L 43.71875 7.71875 L 42.28125 6.28125 L 25 23.5625 Z\"><\/path>\n        <\/svg>\n    <\/button>\n    <div class=\"accomodations__dialog__wrapper\">\n        <iframe id=\"iframeContent\" src=\"\" frameborder=\"0\"><\/iframe>\n    <\/div>\n<\/div>\n<div id=\"roomTourOverlay\" class=\"accomodations__dialog__overlay\"><\/div><\/div>\n\n\n\n<div id=\"accommodation-cta\" class=\"accommodation-cta\">\n    <div class=\"c-appeared\">\n        <div class=\"container\">\n            <div class=\"accommodation-cta__row\">\n                                    <h2 class=\"accommodation-cta__title\">View 5 Bedroom Wilson Village Home 33 Rates<\/h2>\n                                <a href=\"https:\/\/www.montage.com\/palmettobluff\/montage-reservations\/#\/booking\/step-1?room=33\" aria-label=\"Read about \/booking\/step 1?room=33\" target=\"_blank\" aria-describedby=\"new-tab-description\" rel=\"noopener noreferrer\" class=\"accommodation-cta__link\">Reserve this accommodation<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div id=\"accommodation-slider\" class=\"page-section page-section-- c-spacing__bottom-- c-spacing__top-- slider\">\n    <div class=\"listing listing-double c-appeared c-appeared--down\">\n        <div class=\"listing-double__container listing-double__container--slider\">\n                        <div class=\"offer-box__slider slider__swiper\">\n                <div class=\"swiper-wrapper\">\n                                                                        <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc1c7f68566482816.jpg\" alt=\"5 Bedroom Wilson Village Home 33 3\" width=\"1200\" height=\"825\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc19f2e6898759217.jpg\" alt=\"5 Bedroom Wilson Village Home 33 4\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc1e15aa766955650.jpg\" alt=\"5 Bedroom Wilson Village Home 33 5\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc0e4b52466286639.jpg\" alt=\"5 Bedroom Wilson Village Home 33 6\" width=\"1200\" height=\"875\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc10ab14454569108.jpg\" alt=\"5 Bedroom Wilson Village Home 33 7\" width=\"1200\" height=\"728\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc201025922814385.jpg\" alt=\"5 Bedroom Wilson Village Home 33 8\" width=\"1200\" height=\"751\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc114950500799166.jpg\" alt=\"5 Bedroom Wilson Village Home 33 9\" width=\"1200\" height=\"801\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc220c74222847183.jpg\" alt=\"5 Bedroom Wilson Village Home 33 10\" width=\"1200\" height=\"999\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc3073d4289570994.jpg\" alt=\"5 Bedroom Wilson Village Home 33 11\" width=\"1200\" height=\"765\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc2e6123705235084.jpg\" alt=\"5 Bedroom Wilson Village Home 33 12\" width=\"1200\" height=\"760\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc12af5c393285568.jpg\" alt=\"5 Bedroom Wilson Village Home 33 13\" width=\"1200\" height=\"755\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc2bef7c317059785.jpg\" alt=\"5 Bedroom Wilson Village Home 33 14\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc320fe9766548252.jpg\" alt=\"5 Bedroom Wilson Village Home 33 15\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc0c7712490907905.jpg\" alt=\"5 Bedroom Wilson Village Home 33 16\" width=\"1200\" height=\"723\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc2381fb349759713.jpg\" alt=\"5 Bedroom Wilson Village Home 33 17\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc15c9c0766262066.jpg\" alt=\"5 Bedroom Wilson Village Home 33 18\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc2adfc6221266574.jpg\" alt=\"5 Bedroom Wilson Village Home 33 19\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc16e808476919712.jpg\" alt=\"5 Bedroom Wilson Village Home 33 20\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc17f429518641742.jpg\" alt=\"5 Bedroom Wilson Village Home 33 21\" width=\"1200\" height=\"800\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                                                                <div class=\"slider__slide slider__slide--listing swiper-slide\">\n                                                                    <img data-src=\"https:\/\/d1t1qzzb2zwrre.cloudfront.net\/master\/room\/69\/69f90dc3402ef637979463.jpg\" alt=\"5 Bedroom Wilson Village Home 33 22\" width=\"1620\" height=\"1080\" class=\"slider__image slider__image--listing swiper-lazy\">\n                                                                <div class=\"c-swiper-preloader swiper-lazy-preloader\"><\/div>\n                            <\/div>\n                                                            <\/div>\n                                    <div class=\"slider__navigation\">\n                        <button type=\"button\" aria-label=\"slider previous\" class=\"slider__btn slider__btn--prev\">\n                            <div class=\"c-arrow slider__arrow\"><\/div>\n                        <\/button>\n                        <div class=\"slider__pagination offer-box__pagination offer-box__pagination--white swiper-pagination align-items-center\" role=\"navigation\" aria-label=\"Pagination\">&nbsp;<\/div>\n                        <button type=\"button\" aria-label=\"slider next\" class=\"slider__btn slider__btn--next\">\n                            <div class=\"c-arrow slider__arrow\"><\/div>\n                        <\/button>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true},"accommodation-category":[18],"acf":[],"_links":{"self":[{"href":"https:\/\/www.montage.com\/palmettobluff\/wp-json\/wp\/v2\/accommodation\/6481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.montage.com\/palmettobluff\/wp-json\/wp\/v2\/accommodation"}],"about":[{"href":"https:\/\/www.montage.com\/palmettobluff\/wp-json\/wp\/v2\/types\/accommodation"}],"wp:attachment":[{"href":"https:\/\/www.montage.com\/palmettobluff\/wp-json\/wp\/v2\/media?parent=6481"}],"wp:term":[{"taxonomy":"accommodation-category","embeddable":true,"href":"https:\/\/www.montage.com\/palmettobluff\/wp-json\/wp\/v2\/accommodation-category?post=6481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}